{"id":44,"count":9,"description":"","link":"https:\/\/andalini.it\/category\/news\/","name":"News","slug":"news","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>News Archivi - Pastificio Andalini<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"News Archivi - Pastificio Andalini\" \/>\n<meta property=\"og:url\" content=\"https:\/\/andalini.it\/category\/news\/\" \/>\n<meta property=\"og:site_name\" content=\"Pastificio Andalini\" \/>\n<meta property=\"og:image\" content=\"https:\/\/andalini.it\/wp-content\/uploads\/2024\/10\/storia-e-tradizione-andalini-perche-lo-facciamo.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/andalini.it\\\/category\\\/news\\\/\",\"url\":\"https:\\\/\\\/andalini.it\\\/category\\\/news\\\/\",\"name\":\"News Archivi - Pastificio Andalini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/andalini.it\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/andalini.it\\\/category\\\/news\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/andalini.it\\\/category\\\/news\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/andalini.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/andalini.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/andalini.it\\\/en\\\/\",\"name\":\"Pastificio Andalini\",\"description\":\"Esplora l&#039;eccellenza della pasta italiana con il Pastificio Andalini. Dal 1956, produciamo pasta fresca e secca, pasta all&#039;uovo e specialit\u00e0 regionali emiliane, utilizzando solo ingredienti di prima qualit\u00e0. Visita il nostro sito e scopri la vera tradizione della pasta artigianale.\",\"publisher\":{\"@id\":\"https:\\\/\\\/andalini.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/andalini.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/andalini.it\\\/en\\\/#organization\",\"name\":\"Pastificio Andalini\",\"url\":\"https:\\\/\\\/andalini.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/andalini.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/andalini.it\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo-politica-qualita-andalini.webp\",\"contentUrl\":\"https:\\\/\\\/andalini.it\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo-politica-qualita-andalini.webp\",\"width\":600,\"height\":600,\"caption\":\"Pastificio Andalini\"},\"image\":{\"@id\":\"https:\\\/\\\/andalini.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Pastificio.Andalini\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"News Archivi - Pastificio Andalini","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"News Archivi - Pastificio Andalini","og_url":"https:\/\/andalini.it\/category\/news\/","og_site_name":"Pastificio Andalini","og_image":[{"width":940,"height":445,"url":"https:\/\/andalini.it\/wp-content\/uploads\/2024\/10\/storia-e-tradizione-andalini-perche-lo-facciamo.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/andalini.it\/category\/news\/","url":"https:\/\/andalini.it\/category\/news\/","name":"News Archivi - Pastificio Andalini","isPartOf":{"@id":"https:\/\/andalini.it\/en\/#website"},"breadcrumb":{"@id":"https:\/\/andalini.it\/category\/news\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/andalini.it\/category\/news\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/andalini.it\/en\/"},{"@type":"ListItem","position":2,"name":"News"}]},{"@type":"WebSite","@id":"https:\/\/andalini.it\/en\/#website","url":"https:\/\/andalini.it\/en\/","name":"Pastificio Andalini","description":"Esplora l&#039;eccellenza della pasta italiana con il Pastificio Andalini. Dal 1956, produciamo pasta fresca e secca, pasta all&#039;uovo e specialit\u00e0 regionali emiliane, utilizzando solo ingredienti di prima qualit\u00e0. Visita il nostro sito e scopri la vera tradizione della pasta artigianale.","publisher":{"@id":"https:\/\/andalini.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/andalini.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/andalini.it\/en\/#organization","name":"Pastificio Andalini","url":"https:\/\/andalini.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/andalini.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/andalini.it\/wp-content\/uploads\/2025\/11\/logo-politica-qualita-andalini.webp","contentUrl":"https:\/\/andalini.it\/wp-content\/uploads\/2025\/11\/logo-politica-qualita-andalini.webp","width":600,"height":600,"caption":"Pastificio Andalini"},"image":{"@id":"https:\/\/andalini.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Pastificio.Andalini"]}]}},"_links":{"self":[{"href":"https:\/\/andalini.it\/en\/wp-json\/wp\/v2\/categories\/44","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/andalini.it\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/andalini.it\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/andalini.it\/en\/wp-json\/wp\/v2\/posts?categories=44"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}