{"id":2516,"date":"2024-10-22T13:12:52","date_gmt":"2024-10-22T12:12:52","guid":{"rendered":"https:\/\/andalini.it\/?page_id=2516"},"modified":"2026-09-01T15:53:03","modified_gmt":"2026-09-01T14:53:03","slug":"contacts","status":"publish","type":"page","link":"https:\/\/andalini.it\/en\/contacts\/","title":{"rendered":"Contacts"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;4%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;4%&#8221; top_padding_phone=&#8221;10%&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;10%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column top_padding_phone=&#8221;5%&#8221; constrain_group_104=&#8221;yes&#8221; bottom_padding_phone=&#8221;5%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h2&#8243; text_color=&#8221;#005192&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Where We Are&#8221; text_direction=&#8221;default&#8221;][\/split_line_heading][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20px&#8221;][vc_raw_html css=&#8221;&#8221;]PGlmcmFtZSBzdHlsZT0iYm9yZGVyOiAwOyIgc3JjPSJodHRwczovL3d3dy5nb29nbGUuY29tL21hcHMvZW1iZWQ\/cGI9ITFtMTghMW0xMiExbTMhMWQyODMzLjcwMDk2NjM5MzY4ITJkMTEuMjk4MDUzMjEyOTUwODIzITNkNDQuNzQ2MTE3MjMwOTQwOTA0ITJtMyExZjAhMmYwITNmMCEzbTIhMWkxMDI0ITJpNzY4ITRmMTMuMSEzbTMhMW0yITFzMHg0NzdmYjdlNjUwZmM5ODRiJTNBMHgyODY2OTc3MWFkNzI0MzQhMnNQYXN0aWZpY2lvJTIwQW5kYWxpbmklMjBTLnAuQS4hNWUwITNtMiExc2l0ITJzaXQhNHYxNzI5ODQxNDc0MDkwITVtMiExc2l0ITJzaXQiIHdpZHRoPSI2MDAiIGhlaWdodD0iNDUwIiBhbGxvd2Z1bGxzY3JlZW49ImFsbG93ZnVsbHNjcmVlbiI+PC9pZnJhbWU+[\/vc_raw_html][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h2&#8243; text_color=&#8221;#005192&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Contacts&#8221; text_direction=&#8221;default&#8221;][\/split_line_heading][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20px&#8221;][nectar_icon_list animate=&#8221;true&#8221; color=&#8221;Accent-Color&#8221; direction=&#8221;vertical&#8221; icon_size=&#8221;small&#8221; icon_style=&#8221;no-border&#8221;][nectar_icon_list_item icon_type=&#8221;icon&#8221; text_full_html=&#8221;simple&#8221; title=&#8221;List Item&#8221; id=&#8221;1745829225979-0&#8243; tab_id=&#8221;1745829225980-1&#8243; icon_fontawesome=&#8221;fa fa-phone&#8221; text=&#8221;+39 051 6856511&#8243;][\/nectar_icon_list_item][nectar_icon_list_item icon_type=&#8221;icon&#8221; text_full_html=&#8221;simple&#8221; title=&#8221;List Item&#8221; id=&#8221;1745829226021-4&#8243; tab_id=&#8221;1745829226023-9&#8243; icon_fontawesome=&#8221;fa fa-envelope&#8221; text=&#8221;info@andalini.it&#8221;][\/nectar_icon_list_item][nectar_icon_list_item icon_type=&#8221;icon&#8221; text_full_html=&#8221;simple&#8221; title=&#8221;List Item&#8221; id=&#8221;1745829226043-8&#8243; tab_id=&#8221;1745829226045-9&#8243; icon_fontawesome=&#8221;fa fa-map-marker&#8221; text=&#8221;Piazzale Arrigo Andalini, 1 &#8211; 44042 Cento (FE) &#8211; Italy&#8221;][\/nectar_icon_list_item][\/nectar_icon_list][\/vc_column][vc_column top_padding_phone=&#8221;5%&#8221; constrain_group_104=&#8221;yes&#8221; bottom_padding_phone=&#8221;5%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h2&#8243; text_color=&#8221;#005192&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Contact Us&#8221; text_direction=&#8221;default&#8221;][\/split_line_heading][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h3&#8243; text_color=&#8221;#005192&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Write to us, and one of our advisers will contact you within 24\u201348 hours &#8221; text_direction=&#8221;default&#8221;][\/split_line_heading]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f2312-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"2312\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/2516#wpcf7-f2312-o1\" method=\"post\" class=\"wpcf7-form init wpcf7-acceptance-as-validation\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"2312\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f2312-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"First Name and Surname*\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\n<\/p>\n<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"ragione-sociale\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Company Name\" value=\"\" type=\"text\" name=\"ragione-sociale\" \/><\/span> <\/label>\n<\/p>\n<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Your Email Address*\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n<\/p>\n<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Message*\" name=\"your-message\"><\/textarea><\/span> <\/label>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-536\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"acceptance-536\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">I accept the Privacy Policy. We wish to inform you that the personal data you provide will be processed in full compliance with the fundamental principles established by the data protection legislation, including the GDPR 2016\/679. <a href=\"https:\/\/andalini.it\/en\/privacy-policy\/\"><strong>Read the Privacy Policy.<\/strong><\/a><\/span><\/label><\/span><\/span><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Yes, I want to send the message\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;4%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;4%&#8221; top_padding_phone=&#8221;10%&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;10%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column top_padding_phone=&#8221;5%&#8221; constrain_group_104=&#8221;yes&#8221; bottom_padding_phone=&#8221;5%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2516","page","type-page","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contacts - Pastificio Andalini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/andalini.it\/en\/contacts\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contacts - Pastificio Andalini\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;4%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;4%&#8221; top_padding_phone=&#8221;10%&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;10%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column top_padding_phone=&#8221;5%&#8221; constrain_group_104=&#8221;yes&#8221; bottom_padding_phone=&#8221;5%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/andalini.it\/en\/contacts\/\" \/>\n<meta property=\"og:site_name\" content=\"Pastificio Andalini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Pastificio.Andalini\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T14:53:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/andalini.it\/wp-content\/uploads\/2024\/10\/storia-e-tradizione-andalini-perche-lo-facciamo.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/andalini.it\\\/en\\\/contacts\\\/\",\"url\":\"https:\\\/\\\/andalini.it\\\/en\\\/contacts\\\/\",\"name\":\"Contacts - Pastificio Andalini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/andalini.it\\\/en\\\/#website\"},\"datePublished\":\"2024-10-22T12:12:52+00:00\",\"dateModified\":\"2026-09-01T14:53:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/andalini.it\\\/en\\\/contacts\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/andalini.it\\\/en\\\/contacts\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/andalini.it\\\/en\\\/contacts\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/andalini.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contacts\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/andalini.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/andalini.it\\\/en\\\/\",\"name\":\"Pastificio Andalini\",\"description\":\"Esplora l&#039;eccellenza della pasta italiana con il Pastificio Andalini. Dal 1956, produciamo pasta fresca e secca, pasta all&#039;uovo e specialit\u00e0 regionali emiliane, utilizzando solo ingredienti di prima qualit\u00e0. Visita il nostro sito e scopri la vera tradizione della pasta artigianale.\",\"publisher\":{\"@id\":\"https:\\\/\\\/andalini.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/andalini.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/andalini.it\\\/en\\\/#organization\",\"name\":\"Pastificio Andalini\",\"url\":\"https:\\\/\\\/andalini.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/andalini.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/andalini.it\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo-politica-qualita-andalini.webp\",\"contentUrl\":\"https:\\\/\\\/andalini.it\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo-politica-qualita-andalini.webp\",\"width\":600,\"height\":600,\"caption\":\"Pastificio Andalini\"},\"image\":{\"@id\":\"https:\\\/\\\/andalini.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Pastificio.Andalini\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contacts - Pastificio Andalini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/andalini.it\/en\/contacts\/","og_locale":"en_US","og_type":"article","og_title":"Contacts - Pastificio Andalini","og_description":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;4%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;4%&#8221; top_padding_phone=&#8221;10%&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;10%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column top_padding_phone=&#8221;5%&#8221; constrain_group_104=&#8221;yes&#8221; bottom_padding_phone=&#8221;5%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221;...","og_url":"https:\/\/andalini.it\/en\/contacts\/","og_site_name":"Pastificio Andalini","article_publisher":"https:\/\/www.facebook.com\/Pastificio.Andalini","article_modified_time":"2026-09-01T14:53:03+00:00","og_image":[{"width":940,"height":445,"url":"https:\/\/andalini.it\/wp-content\/uploads\/2024\/10\/storia-e-tradizione-andalini-perche-lo-facciamo.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/andalini.it\/en\/contacts\/","url":"https:\/\/andalini.it\/en\/contacts\/","name":"Contacts - Pastificio Andalini","isPartOf":{"@id":"https:\/\/andalini.it\/en\/#website"},"datePublished":"2024-10-22T12:12:52+00:00","dateModified":"2026-09-01T14:53:03+00:00","breadcrumb":{"@id":"https:\/\/andalini.it\/en\/contacts\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/andalini.it\/en\/contacts\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/andalini.it\/en\/contacts\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/andalini.it\/en\/"},{"@type":"ListItem","position":2,"name":"Contacts"}]},{"@type":"WebSite","@id":"https:\/\/andalini.it\/en\/#website","url":"https:\/\/andalini.it\/en\/","name":"Pastificio Andalini","description":"Esplora l&#039;eccellenza della pasta italiana con il Pastificio Andalini. Dal 1956, produciamo pasta fresca e secca, pasta all&#039;uovo e specialit\u00e0 regionali emiliane, utilizzando solo ingredienti di prima qualit\u00e0. Visita il nostro sito e scopri la vera tradizione della pasta artigianale.","publisher":{"@id":"https:\/\/andalini.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/andalini.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/andalini.it\/en\/#organization","name":"Pastificio Andalini","url":"https:\/\/andalini.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/andalini.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/andalini.it\/wp-content\/uploads\/2025\/11\/logo-politica-qualita-andalini.webp","contentUrl":"https:\/\/andalini.it\/wp-content\/uploads\/2025\/11\/logo-politica-qualita-andalini.webp","width":600,"height":600,"caption":"Pastificio Andalini"},"image":{"@id":"https:\/\/andalini.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Pastificio.Andalini"]}]}},"_links":{"self":[{"href":"https:\/\/andalini.it\/en\/wp-json\/wp\/v2\/pages\/2516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/andalini.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/andalini.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/andalini.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/andalini.it\/en\/wp-json\/wp\/v2\/comments?post=2516"}],"version-history":[{"count":2,"href":"https:\/\/andalini.it\/en\/wp-json\/wp\/v2\/pages\/2516\/revisions"}],"predecessor-version":[{"id":2519,"href":"https:\/\/andalini.it\/en\/wp-json\/wp\/v2\/pages\/2516\/revisions\/2519"}],"wp:attachment":[{"href":"https:\/\/andalini.it\/en\/wp-json\/wp\/v2\/media?parent=2516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}