{"id":2568,"date":"2024-10-23T14:19:46","date_gmt":"2024-10-23T13:19:46","guid":{"rendered":"https:\/\/andalini.it\/?page_id=2568"},"modified":"2026-09-01T15:50:08","modified_gmt":"2026-09-01T14:50:08","slug":"semola-selection","status":"publish","type":"page","link":"https:\/\/andalini.it\/en\/retail\/semola-selection\/","title":{"rendered":"Semola Selection"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;268&#8243; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;5%&#8221; top_padding_phone=&#8221;20%&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;20%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; enable_gradient=&#8221;true&#8221; color_overlay=&#8221;rgba(243,243,243,0.01)&#8221; color_overlay_2=&#8221;#f3f3f3&#8243; overlay_strength=&#8221;0.95&#8243; gradient_direction=&#8221;top_to_bottom&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;50px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;1659&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h2&#8243; text_color=&#8221;#d89f5a&#8221; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Pasta with original shapes and a unique flavour&#8221; text_direction=&#8221;default&#8221; max_width=&#8221;600px&#8221;][\/split_line_heading][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]The different shapes, colours and blends, created using a variety of ingredients, give this range a distinctive and unmistakable character. The <em><strong>Selection range<\/strong><\/em> is designed to inspire creativity in the kitchen while maintaining the highest standards of <strong>quality<\/strong>.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#f3f3f3&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;2%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;2%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;tagliatelle&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h2&#8243; text_color=&#8221;#d89f5a&#8221; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Semola Selection&#8221; text_direction=&#8221;default&#8221;][\/split_line_heading][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h3&#8243; text_color=&#8221;#d89f5a&#8221; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Pasta with original shapes and a unique flavour&#8221; text_direction=&#8221;default&#8221;][\/split_line_heading][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221; max_width=&#8221;700px&#8221;]Semola Selection is a range of premium-quality pasta made with <strong>100% Italian durum wheat semolina<\/strong>, born from our passion for tradition and attention to detail. The use of selected Italian durum wheat and <strong>bronze die cut extrusion<\/strong> results in pasta with a rich flavour and a porous texture that remains perfectly al dente after cooking.<\/p>\n<p>But that\u2019s not all: Semola Selection offers a <strong>wide variety of pasta shapes<\/strong>, including smooth, ridged and two-tone Gramigna, as well as bronze cut Spaghettoni, to satisfy every taste. Thanks to its ability to <strong>retain its shape during cooking<\/strong>, this pasta is ideal for creating flavourful and nourishing dishes to accompany all kinds of sauces, particularly meat-based recipes.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#f3f3f3&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;2%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;2%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;tagliatelle&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h2&#8243; text_color=&#8221;#d89f5a&#8221; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Smooth Gramigne&#8221; text_direction=&#8221;default&#8221;][\/split_line_heading][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221; max_width=&#8221;700px&#8221;]Smooth Gramigna pasta has a distinctive shape that resembles the tiny seed of a plant from the grass family. The pasta is made from a simple dough consisting of 100% Italian durum wheat semolina and water. Deeply rooted in the traditions of Emilia, this pasta shape is produced in accordance with the time-honoured customs of our region. We recommend serving it with a sausage-based sauce or, alternatively, a rich Bolognese rag\u00f9.[\/vc_column_text][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;20px&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;20px&#8221; left_padding_desktop=&#8221;20%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;20%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;prodotti-cat&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;]<div class=\"woocommerce columns-3 \"><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#f3f3f3&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;2%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;2%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;tagliatelle&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h2&#8243; text_color=&#8221;#d89f5a&#8221; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Ridged Gramigna Paglia e Fieno&#8221; text_direction=&#8221;default&#8221;][\/split_line_heading][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221; max_width=&#8221;700px&#8221;]La Gramigna Rigata Paglia e Fieno \u00e8 un&#8217;evoluzione della tradizionale gramigna liscia, in questo caso parte dell&#8217;impasto \u00e8 lavorato con spinaci che regalano un caratteristico colore alla pasta. Realizzata in versione rigata, questa Gramigna si lega ancor di pi\u00f9 al condimento, regalando un boccone saporito e intenso.<\/p>\n<p>Ridged Gramigna Paglia e Fieno is an evolution of the traditional smooth Gramigna; in this version, part of the dough is blended with spinach, giving the pasta its distinctive colour. Produced in a ridged format, this Gramigna holds sauces even more effectively, delivering a rich and satisfying flavour.<\/p>\n<p>The most recommended pairing is with a Bolognese rag\u00f9 or, more generally, a meat-based sauce; however, a version with cream, ham and peas is also well worth trying.[\/vc_column_text][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;20px&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;20px&#8221; left_padding_desktop=&#8221;20%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;20%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;prodotti-cat&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;]<div class=\"woocommerce columns-3 \"><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#f3f3f3&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;2%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;2%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;tagliatelle&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h2&#8243; text_color=&#8221;#d89f5a&#8221; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Bronze cut Spaghettoni&#8221; text_direction=&#8221;default&#8221;][\/split_line_heading][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221; max_width=&#8221;700px&#8221;]Spaghettoni is a pasta shape made from 100% Italian durum wheat semolina, featuring a rough-textured surface created through bronze die cut extrusion and slow drying, making it ideal for absorbing sauces. An undisputed symbol of Mediterranean cuisine, bronze cut Spaghettoni offers the exceptional flavour of the finest semolina; enjoy it with a delicate tomato sauce or a more creative recipe featuring vegetables, fish or meat.[\/vc_column_text][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;20px&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;20px&#8221; left_padding_desktop=&#8221;20%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;20%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; el_class=&#8221;prodotti-cat&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;]<div class=\"woocommerce columns-3 \"><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;268&#8243; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;5%&#8221; top_padding_phone=&#8221;20%&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;20%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; enable_gradient=&#8221;true&#8221; color_overlay=&#8221;rgba(243,243,243,0.01)&#8221; color_overlay_2=&#8221;#f3f3f3&#8243; overlay_strength=&#8221;0.95&#8243; gradient_direction=&#8221;top_to_bottom&#8221; shape_divider_position=&#8221;bottom&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":2165,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2568","page","type-page","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Semola Selection - Pastificio Andalini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/andalini.it\/en\/retail\/semola-selection\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Semola Selection - Pastificio Andalini\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;268&#8243; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;5%&#8221; top_padding_phone=&#8221;20%&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;20%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; enable_gradient=&#8221;true&#8221; color_overlay=&#8221;rgba(243,243,243,0.01)&#8221; color_overlay_2=&#8221;#f3f3f3&#8243; overlay_strength=&#8221;0.95&#8243; gradient_direction=&#8221;top_to_bottom&#8221; shape_divider_position=&#8221;bottom&#8221;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/andalini.it\/en\/retail\/semola-selection\/\" \/>\n<meta property=\"og:site_name\" content=\"Pastificio Andalini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Pastificio.Andalini\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T14:50:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/andalini.it\/wp-content\/uploads\/2024\/10\/storia-e-tradizione-andalini-perche-lo-facciamo.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/andalini.it\\\/en\\\/retail\\\/semola-selection\\\/\",\"url\":\"https:\\\/\\\/andalini.it\\\/en\\\/retail\\\/semola-selection\\\/\",\"name\":\"Semola Selection - Pastificio Andalini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/andalini.it\\\/en\\\/#website\"},\"datePublished\":\"2024-10-23T13:19:46+00:00\",\"dateModified\":\"2026-09-01T14:50:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/andalini.it\\\/en\\\/retail\\\/semola-selection\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/andalini.it\\\/en\\\/retail\\\/semola-selection\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/andalini.it\\\/en\\\/retail\\\/semola-selection\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/andalini.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retail\",\"item\":\"https:\\\/\\\/andalini.it\\\/en\\\/retail\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Semola Selection\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/andalini.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/andalini.it\\\/en\\\/\",\"name\":\"Pastificio Andalini\",\"description\":\"Esplora l&#039;eccellenza della pasta italiana con il Pastificio Andalini. Dal 1956, produciamo pasta fresca e secca, pasta all&#039;uovo e specialit\u00e0 regionali emiliane, utilizzando solo ingredienti di prima qualit\u00e0. Visita il nostro sito e scopri la vera tradizione della pasta artigianale.\",\"publisher\":{\"@id\":\"https:\\\/\\\/andalini.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/andalini.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/andalini.it\\\/en\\\/#organization\",\"name\":\"Pastificio Andalini\",\"url\":\"https:\\\/\\\/andalini.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/andalini.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/andalini.it\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo-politica-qualita-andalini.webp\",\"contentUrl\":\"https:\\\/\\\/andalini.it\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo-politica-qualita-andalini.webp\",\"width\":600,\"height\":600,\"caption\":\"Pastificio Andalini\"},\"image\":{\"@id\":\"https:\\\/\\\/andalini.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Pastificio.Andalini\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Semola Selection - Pastificio Andalini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/andalini.it\/en\/retail\/semola-selection\/","og_locale":"en_US","og_type":"article","og_title":"Semola Selection - Pastificio Andalini","og_description":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;268&#8243; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;5%&#8221; top_padding_phone=&#8221;20%&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;20%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; enable_gradient=&#8221;true&#8221; color_overlay=&#8221;rgba(243,243,243,0.01)&#8221; color_overlay_2=&#8221;#f3f3f3&#8243; overlay_strength=&#8221;0.95&#8243; gradient_direction=&#8221;top_to_bottom&#8221; shape_divider_position=&#8221;bottom&#8221;...","og_url":"https:\/\/andalini.it\/en\/retail\/semola-selection\/","og_site_name":"Pastificio Andalini","article_publisher":"https:\/\/www.facebook.com\/Pastificio.Andalini","article_modified_time":"2026-09-01T14:50:08+00:00","og_image":[{"width":940,"height":445,"url":"https:\/\/andalini.it\/wp-content\/uploads\/2024\/10\/storia-e-tradizione-andalini-perche-lo-facciamo.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/andalini.it\/en\/retail\/semola-selection\/","url":"https:\/\/andalini.it\/en\/retail\/semola-selection\/","name":"Semola Selection - Pastificio Andalini","isPartOf":{"@id":"https:\/\/andalini.it\/en\/#website"},"datePublished":"2024-10-23T13:19:46+00:00","dateModified":"2026-09-01T14:50:08+00:00","breadcrumb":{"@id":"https:\/\/andalini.it\/en\/retail\/semola-selection\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/andalini.it\/en\/retail\/semola-selection\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/andalini.it\/en\/retail\/semola-selection\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/andalini.it\/en\/"},{"@type":"ListItem","position":2,"name":"Retail","item":"https:\/\/andalini.it\/en\/retail\/"},{"@type":"ListItem","position":3,"name":"Semola Selection"}]},{"@type":"WebSite","@id":"https:\/\/andalini.it\/en\/#website","url":"https:\/\/andalini.it\/en\/","name":"Pastificio Andalini","description":"Esplora l&#039;eccellenza della pasta italiana con il Pastificio Andalini. Dal 1956, produciamo pasta fresca e secca, pasta all&#039;uovo e specialit\u00e0 regionali emiliane, utilizzando solo ingredienti di prima qualit\u00e0. Visita il nostro sito e scopri la vera tradizione della pasta artigianale.","publisher":{"@id":"https:\/\/andalini.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/andalini.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/andalini.it\/en\/#organization","name":"Pastificio Andalini","url":"https:\/\/andalini.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/andalini.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/andalini.it\/wp-content\/uploads\/2025\/11\/logo-politica-qualita-andalini.webp","contentUrl":"https:\/\/andalini.it\/wp-content\/uploads\/2025\/11\/logo-politica-qualita-andalini.webp","width":600,"height":600,"caption":"Pastificio Andalini"},"image":{"@id":"https:\/\/andalini.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Pastificio.Andalini"]}]}},"_links":{"self":[{"href":"https:\/\/andalini.it\/en\/wp-json\/wp\/v2\/pages\/2568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/andalini.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/andalini.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/andalini.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/andalini.it\/en\/wp-json\/wp\/v2\/comments?post=2568"}],"version-history":[{"count":3,"href":"https:\/\/andalini.it\/en\/wp-json\/wp\/v2\/pages\/2568\/revisions"}],"predecessor-version":[{"id":2632,"href":"https:\/\/andalini.it\/en\/wp-json\/wp\/v2\/pages\/2568\/revisions\/2632"}],"up":[{"embeddable":true,"href":"https:\/\/andalini.it\/en\/wp-json\/wp\/v2\/pages\/2165"}],"wp:attachment":[{"href":"https:\/\/andalini.it\/en\/wp-json\/wp\/v2\/media?parent=2568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}