{"id":2483,"date":"2024-11-05T10:34:35","date_gmt":"2024-11-05T09:34:35","guid":{"rendered":"https:\/\/andalini.it\/prodotto\/16-avena\/"},"modified":"2026-09-01T15:44:28","modified_gmt":"2026-09-01T14:44:28","slug":"16-avena","status":"publish","type":"product","link":"https:\/\/andalini.it\/en\/prodotto\/16-avena\/","title":{"rendered":"16 Avena"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h4&#8243; text_color=&#8221;#005192&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;&lt;p&gt;Storage&lt;\/p&gt;&#8221; text_direction=&#8221;default&#8221;][\/split_line_heading][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<p>Store away from heat sources and direct sunlight, and avoid damp environments.<\/p>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h4&#8243; text_color=&#8221;#b7b1a9&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;&lt;p&gt;Allergens&lt;\/p&gt;&#8221; text_direction=&#8221;default&#8221;][\/split_line_heading][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<p>May contain traces of soya and mustard.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>Egg pasta.<\/p>\n<p><strong>Ingredients:<\/strong><br \/>\nDurum wheat semolina, eggs 20%.<\/p>\n<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][text-with-icon icon_type=\"image_icon\" icon_image=\"575\"]<strong>100% Italian eggs from free-range hens<\/strong>[\/text-with-icon][text-with-icon icon_type=\"image_icon\" icon_image=\"577\"]<strong>100% Italian wheat<\/strong>[\/text-with-icon][text-with-icon icon_type=\"image_icon\" icon_image=\"576\"]<strong>Cooking time: 5\u20136 minutes<\/strong>[\/text-with-icon][\/vc_column][\/vc_row]<\/p>\n<div class=\"tabella-nutrizionale\">\n<h3>Average values per 100 g of product:<\/h3>\n<table class=\"nutrition-table\">\n<tbody>\n<tr>\n<td>Energy<\/td>\n<td>1527 kJ\/361 kcal<\/td>\n<\/tr>\n<tr>\n<td>Fat<\/td>\n<td>3.3 g<\/td>\n<\/tr>\n<tr>\n<td>Of which saturated fatty acids<\/td>\n<td>1.5 g<\/td>\n<\/tr>\n<tr>\n<td>Carbohydrates<\/td>\n<td>68 g<\/td>\n<\/tr>\n<tr>\n<td>Of which sugars<\/td>\n<td>2 g<\/td>\n<\/tr>\n<tr>\n<td>Fibre<\/td>\n<td>2.8 g<\/td>\n<\/tr>\n<tr>\n<td>Protein<\/td>\n<td>13 g<\/td>\n<\/tr>\n<tr>\n<td>Salt<\/td>\n<td>0.10 g<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n","protected":false},"featured_media":2481,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[74],"product_tag":[],"class_list":["post-2483","product","type-product","status-publish","has-post-thumbnail","product_cat-small-pasta-shapes","first","instock","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>16 Avena - Pastificio Andalini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/andalini.it\/en\/prodotto\/16-avena\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"16 Avena - Pastificio Andalini\" \/>\n<meta property=\"og:description\" content=\"Egg pasta.  Ingredients: Durum wheat semolina, eggs 20%.  [vc_row type=&quot;in_container&quot; full_screen_row_position=&quot;middle&quot; column_margin=&quot;default&quot; column_direction=&quot;default&quot; column_direction_tablet=&quot;default&quot; column_direction_phone=&quot;default&quot; scene_position=&quot;center&quot; text_color=&quot;dark&quot; text_align=&quot;left&quot; row_border_radius=&quot;none&quot; row_border_radius_applies=&quot;bg&quot; overflow=&quot;visible&quot; overlay_strength=&quot;0.3&quot; gradient_direction=&quot;left_to_right&quot; shape_divider_position=&quot;bottom&quot; bg_image_animation=&quot;none&quot;][vc_column column_padding=&quot;no-extra-padding&quot; column_padding_tablet=&quot;inherit&quot; column_padding_phone=&quot;inherit&quot; column_padding_position=&quot;all&quot; column_element_direction_desktop=&quot;default&quot; column_element_spacing=&quot;default&quot; desktop_text_alignment=&quot;default&quot; tablet_text_alignment=&quot;default&quot; phone_text_alignment=&quot;default&quot; background_color_opacity=&quot;1&quot; background_hover_color_opacity=&quot;1&quot; column_backdrop_filter=&quot;none&quot; column_shadow=&quot;none&quot; column_border_radius=&quot;none&quot; column_link_target=&quot;_self&quot; column_position=&quot;default&quot; gradient_direction=&quot;left_to_right&quot; overlay_strength=&quot;0.3&quot; width=&quot;1\/1&quot; tablet_width_inherit=&quot;default&quot; animation_type=&quot;default&quot; bg_image_animation=&quot;none&quot; border_type=&quot;simple&quot; column_border_width=&quot;none&quot; column_border_style=&quot;solid&quot;][\/vc_column][\/vc_row]  Average values per 100 g of product:    Energy 1527 kJ\/361 kcal   Fat 3.3 g   Of which saturated fatty acids 1.5 g   Carbohydrates 68 g   Of which sugars 2 g   Fibre 2.8 g   Protein 13 g   Salt 0.10 g\" \/>\n<meta property=\"og:url\" content=\"https:\/\/andalini.it\/en\/prodotto\/16-avena\/\" \/>\n<meta property=\"og:site_name\" content=\"Pastificio Andalini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Pastificio.Andalini\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T14:44:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/andalini.it\/wp-content\/uploads\/2024\/11\/16-avena-antica-tradizione-andalini.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/andalini.it\\\/en\\\/prodotto\\\/16-avena\\\/\",\"url\":\"https:\\\/\\\/andalini.it\\\/en\\\/prodotto\\\/16-avena\\\/\",\"name\":\"16 Avena - Pastificio Andalini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/andalini.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/andalini.it\\\/en\\\/prodotto\\\/16-avena\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/andalini.it\\\/en\\\/prodotto\\\/16-avena\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/andalini.it\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/16-avena-antica-tradizione-andalini.webp\",\"datePublished\":\"2024-11-05T09:34:35+00:00\",\"dateModified\":\"2026-09-01T14:44:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/andalini.it\\\/en\\\/prodotto\\\/16-avena\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/andalini.it\\\/en\\\/prodotto\\\/16-avena\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/andalini.it\\\/en\\\/prodotto\\\/16-avena\\\/#primaryimage\",\"url\":\"https:\\\/\\\/andalini.it\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/16-avena-antica-tradizione-andalini.webp\",\"contentUrl\":\"https:\\\/\\\/andalini.it\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/16-avena-antica-tradizione-andalini.webp\",\"width\":1800,\"height\":1800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/andalini.it\\\/en\\\/prodotto\\\/16-avena\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/andalini.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/andalini.it\\\/en\\\/?page_id=2261\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"16 Avena\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/andalini.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/andalini.it\\\/en\\\/\",\"name\":\"Pastificio Andalini\",\"description\":\"Esplora l&#039;eccellenza della pasta italiana con il Pastificio Andalini. Dal 1956, produciamo pasta fresca e secca, pasta all&#039;uovo e specialit\u00e0 regionali emiliane, utilizzando solo ingredienti di prima qualit\u00e0. Visita il nostro sito e scopri la vera tradizione della pasta artigianale.\",\"publisher\":{\"@id\":\"https:\\\/\\\/andalini.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/andalini.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/andalini.it\\\/en\\\/#organization\",\"name\":\"Pastificio Andalini\",\"url\":\"https:\\\/\\\/andalini.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/andalini.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/andalini.it\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo-politica-qualita-andalini.webp\",\"contentUrl\":\"https:\\\/\\\/andalini.it\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo-politica-qualita-andalini.webp\",\"width\":600,\"height\":600,\"caption\":\"Pastificio Andalini\"},\"image\":{\"@id\":\"https:\\\/\\\/andalini.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Pastificio.Andalini\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"16 Avena - Pastificio Andalini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/andalini.it\/en\/prodotto\/16-avena\/","og_locale":"en_US","og_type":"article","og_title":"16 Avena - Pastificio Andalini","og_description":"Egg pasta.  Ingredients: Durum wheat semolina, eggs 20%.  [vc_row type=\"in_container\" full_screen_row_position=\"middle\" column_margin=\"default\" column_direction=\"default\" column_direction_tablet=\"default\" column_direction_phone=\"default\" scene_position=\"center\" text_color=\"dark\" text_align=\"left\" row_border_radius=\"none\" row_border_radius_applies=\"bg\" overflow=\"visible\" overlay_strength=\"0.3\" gradient_direction=\"left_to_right\" shape_divider_position=\"bottom\" bg_image_animation=\"none\"][vc_column column_padding=\"no-extra-padding\" column_padding_tablet=\"inherit\" column_padding_phone=\"inherit\" column_padding_position=\"all\" column_element_direction_desktop=\"default\" column_element_spacing=\"default\" desktop_text_alignment=\"default\" tablet_text_alignment=\"default\" phone_text_alignment=\"default\" background_color_opacity=\"1\" background_hover_color_opacity=\"1\" column_backdrop_filter=\"none\" column_shadow=\"none\" column_border_radius=\"none\" column_link_target=\"_self\" column_position=\"default\" gradient_direction=\"left_to_right\" overlay_strength=\"0.3\" width=\"1\/1\" tablet_width_inherit=\"default\" animation_type=\"default\" bg_image_animation=\"none\" border_type=\"simple\" column_border_width=\"none\" column_border_style=\"solid\"][\/vc_column][\/vc_row]  Average values per 100 g of product:    Energy 1527 kJ\/361 kcal   Fat 3.3 g   Of which saturated fatty acids 1.5 g   Carbohydrates 68 g   Of which sugars 2 g   Fibre 2.8 g   Protein 13 g   Salt 0.10 g","og_url":"https:\/\/andalini.it\/en\/prodotto\/16-avena\/","og_site_name":"Pastificio Andalini","article_publisher":"https:\/\/www.facebook.com\/Pastificio.Andalini","article_modified_time":"2026-09-01T14:44:28+00:00","og_image":[{"width":1800,"height":1800,"url":"https:\/\/andalini.it\/wp-content\/uploads\/2024\/11\/16-avena-antica-tradizione-andalini.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/andalini.it\/en\/prodotto\/16-avena\/","url":"https:\/\/andalini.it\/en\/prodotto\/16-avena\/","name":"16 Avena - Pastificio Andalini","isPartOf":{"@id":"https:\/\/andalini.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/andalini.it\/en\/prodotto\/16-avena\/#primaryimage"},"image":{"@id":"https:\/\/andalini.it\/en\/prodotto\/16-avena\/#primaryimage"},"thumbnailUrl":"https:\/\/andalini.it\/wp-content\/uploads\/2024\/11\/16-avena-antica-tradizione-andalini.webp","datePublished":"2024-11-05T09:34:35+00:00","dateModified":"2026-09-01T14:44:28+00:00","breadcrumb":{"@id":"https:\/\/andalini.it\/en\/prodotto\/16-avena\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/andalini.it\/en\/prodotto\/16-avena\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/andalini.it\/en\/prodotto\/16-avena\/#primaryimage","url":"https:\/\/andalini.it\/wp-content\/uploads\/2024\/11\/16-avena-antica-tradizione-andalini.webp","contentUrl":"https:\/\/andalini.it\/wp-content\/uploads\/2024\/11\/16-avena-antica-tradizione-andalini.webp","width":1800,"height":1800},{"@type":"BreadcrumbList","@id":"https:\/\/andalini.it\/en\/prodotto\/16-avena\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/andalini.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/andalini.it\/en\/?page_id=2261"},{"@type":"ListItem","position":3,"name":"16 Avena"}]},{"@type":"WebSite","@id":"https:\/\/andalini.it\/en\/#website","url":"https:\/\/andalini.it\/en\/","name":"Pastificio Andalini","description":"Esplora l&#039;eccellenza della pasta italiana con il Pastificio Andalini. Dal 1956, produciamo pasta fresca e secca, pasta all&#039;uovo e specialit\u00e0 regionali emiliane, utilizzando solo ingredienti di prima qualit\u00e0. Visita il nostro sito e scopri la vera tradizione della pasta artigianale.","publisher":{"@id":"https:\/\/andalini.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/andalini.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/andalini.it\/en\/#organization","name":"Pastificio Andalini","url":"https:\/\/andalini.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/andalini.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/andalini.it\/wp-content\/uploads\/2025\/11\/logo-politica-qualita-andalini.webp","contentUrl":"https:\/\/andalini.it\/wp-content\/uploads\/2025\/11\/logo-politica-qualita-andalini.webp","width":600,"height":600,"caption":"Pastificio Andalini"},"image":{"@id":"https:\/\/andalini.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Pastificio.Andalini"]}]}},"_links":{"self":[{"href":"https:\/\/andalini.it\/en\/wp-json\/wp\/v2\/product\/2483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/andalini.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/andalini.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/andalini.it\/en\/wp-json\/wp\/v2\/comments?post=2483"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/andalini.it\/en\/wp-json\/wp\/v2\/media\/2481"}],"wp:attachment":[{"href":"https:\/\/andalini.it\/en\/wp-json\/wp\/v2\/media?parent=2483"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/andalini.it\/en\/wp-json\/wp\/v2\/product_brand?post=2483"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/andalini.it\/en\/wp-json\/wp\/v2\/product_cat?post=2483"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/andalini.it\/en\/wp-json\/wp\/v2\/product_tag?post=2483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}